{"id":296,"date":"2016-02-25T14:19:43","date_gmt":"2016-02-25T17:19:43","guid":{"rendered":"https:\/\/conteudo.gerenteweb.com.br\/blog?p=296"},"modified":"2020-11-10T17:57:20","modified_gmt":"2020-11-10T20:57:20","slug":"metricas-nas-redes-sociais","status":"publish","type":"post","link":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/","title":{"rendered":"M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital"},"content":{"rendered":"<p>As m\u00eddias sociais, aliadas a eficientes estrat\u00e9gias de marketing de conte\u00fado, s\u00e3o hoje um dos mais poderosos canais para a cria\u00e7\u00e3o e manuten\u00e7\u00e3o de relacionamento e engajamento das marcas com seus p\u00fablicos.\u00a0Atrav\u00e9s de campanhas assertivas \u00e9 poss\u00edvel conhecer a fundo o comportamento e opini\u00e3o do seu consumidor e o que ele pensa sobre o seu produto ou servi\u00e7o. At\u00e9 aqui n\u00e3o deve ser nenhuma novidade para voc\u00ea, certo?<\/p>\n<p>Mas, voc\u00ea tamb\u00e9m deve saber que n\u00e3o basta apenas produzir um bom conte\u00fado para seu p\u00fablico ou produzir boas campanhas e promo\u00e7\u00f5es ou fazer an\u00fancios patrocinados. Al\u00e9m disso, tamb\u00e9m \u00e9 muito importante saber analisar (frequentemente) os dados, n\u00fameros e resultados apontados pelos relat\u00f3rios nas redes sociais. S\u00e3o as famosas m\u00e9tricas.<\/p>\n<p>Com a an\u00e1lise das m\u00e9tricas \u00e9 poss\u00edvel medir o alcance das suas publica\u00e7\u00f5es, os posts que mais tiveram intera\u00e7\u00e3o e compartilhamento entre os usu\u00e1rios, o aumento de visualiza\u00e7\u00f5es na p\u00e1gina e nos posts e, a partir disso, analisar se as suas a\u00e7\u00f5es e estrat\u00e9gias de conte\u00fado nas redes sociais trouxeram resultados positivos e, claro, convers\u00e3o. Mensurar o resultado de campanhas tamb\u00e9m pode identificar o que n\u00e3o est\u00e1 dando certo e, se for o caso, mudar o rumo da sua campanha dependendo dos resultados apresentados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As m\u00eddias sociais, aliadas a eficientes estrat\u00e9gias de marketing de conte\u00fado, s\u00e3o hoje um dos mais poderosos canais para a cria\u00e7\u00e3o e manuten\u00e7\u00e3o de relacionamento e engajamento das marcas com seus p\u00fablicos.\u00a0Atrav\u00e9s de campanhas assertivas \u00e9 poss\u00edvel conhecer a fundo o comportamento e opini\u00e3o do seu consumidor e o que ele pensa sobre o seu &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital&#8221;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!<\/title>\n<meta name=\"description\" content=\"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!\" \/>\n<meta property=\"og:description\" content=\"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/\" \/>\n<meta property=\"og:site_name\" content=\"GerenteWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Gerenteweb\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-25T17:19:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-10T20:57:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GerenteWeb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gerenteweb\" \/>\n<meta name=\"twitter:site\" content=\"@gerenteweb\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GerenteWeb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/\"},\"author\":{\"name\":\"GerenteWeb\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4c19d08ba068b4c557ff9cb116512a9e\"},\"headline\":\"M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital\",\"datePublished\":\"2016-02-25T17:19:43+00:00\",\"dateModified\":\"2020-11-10T20:57:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/\"},\"wordCount\":257,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/img-15.jpg\",\"articleSection\":[\"Marketing Digital\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/\",\"name\":\"M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/img-15.jpg\",\"datePublished\":\"2016-02-25T17:19:43+00:00\",\"dateModified\":\"2020-11-10T20:57:20+00:00\",\"description\":\"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/img-15.jpg\",\"contentUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/img-15.jpg\",\"width\":900,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/metricas-nas-redes-sociais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\",\"name\":\"GerenteWeb\",\"description\":\"Marketing Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\",\"name\":\"GerenteWeb\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo-gerenteweb.png\",\"contentUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo-gerenteweb.png\",\"width\":229,\"height\":54,\"caption\":\"GerenteWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Gerenteweb\\\/\",\"https:\\\/\\\/x.com\\\/gerenteweb\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gerenteweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/4c19d08ba068b4c557ff9cb116512a9e\",\"name\":\"GerenteWeb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"caption\":\"GerenteWeb\"},\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/author\\\/gerenteweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!","description":"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!","og_description":"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!","og_url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/","og_site_name":"GerenteWeb","article_publisher":"https:\/\/www.facebook.com\/Gerenteweb\/","article_published_time":"2016-02-25T17:19:43+00:00","article_modified_time":"2020-11-10T20:57:20+00:00","og_image":[{"width":900,"height":300,"url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg","type":"image\/jpeg"}],"author":"GerenteWeb","twitter_card":"summary_large_image","twitter_creator":"@gerenteweb","twitter_site":"@gerenteweb","twitter_misc":{"Written by":"GerenteWeb","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#article","isPartOf":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/"},"author":{"name":"GerenteWeb","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/person\/4c19d08ba068b4c557ff9cb116512a9e"},"headline":"M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital","datePublished":"2016-02-25T17:19:43+00:00","dateModified":"2020-11-10T20:57:20+00:00","mainEntityOfPage":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/"},"wordCount":257,"commentCount":0,"publisher":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg","articleSection":["Marketing Digital"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/","name":"M\u00e9tricas nas redes sociais: saiba a import\u00e2ncia desses indicadores!","isPartOf":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#primaryimage"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#primaryimage"},"thumbnailUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg","datePublished":"2016-02-25T17:19:43+00:00","dateModified":"2020-11-10T20:57:20+00:00","description":"N\u00e3o basta produzir um bom conte\u00fado ou produzir boas campanhas. \u00c9 preciso saber analisar os dados. As m\u00e9trica s\u00e3o essenciais. Entenda!","breadcrumb":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#primaryimage","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg","contentUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/02\/img-15.jpg","width":900,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/metricas-nas-redes-sociais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/conteudo.gerenteweb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"M\u00e9tricas nas redes sociais: conhe\u00e7a a import\u00e2ncia desse indicador para suas a\u00e7\u00f5es de marketing digital"}]},{"@type":"WebSite","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#website","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/","name":"GerenteWeb","description":"Marketing Digital","publisher":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conteudo.gerenteweb.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization","name":"GerenteWeb","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2015\/12\/logo-gerenteweb.png","contentUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2015\/12\/logo-gerenteweb.png","width":229,"height":54,"caption":"GerenteWeb"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Gerenteweb\/","https:\/\/x.com\/gerenteweb","https:\/\/www.linkedin.com\/company\/gerenteweb"]},{"@type":"Person","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/person\/4c19d08ba068b4c557ff9cb116512a9e","name":"GerenteWeb","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","caption":"GerenteWeb"},"url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/author\/gerenteweb\/"}]}},"_links":{"self":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":3,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"predecessor-version":[{"id":1567,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/296\/revisions\/1567"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/media\/407"}],"wp:attachment":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}