{"id":527,"date":"2016-07-15T09:02:38","date_gmt":"2016-07-15T12:02:38","guid":{"rendered":"http:\/\/conteudo.gerenteweb.com.br\/blog\/?p=527"},"modified":"2020-11-12T10:55:19","modified_gmt":"2020-11-12T13:55:19","slug":"redes-sociais-para-conquistar-novos-pacientes","status":"publish","type":"post","link":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/","title":{"rendered":"Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes"},"content":{"rendered":"<p>Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro! A seguir, vamos listar algumas dicas muito interessantes para voc\u00ea come\u00e7ar a explorar esse canal ainda hoje e conquistar novos pacientes.<\/p>\n<p><strong>Entenda a proposta de cada rede<\/strong><\/p>\n<p>Cada rede social tem uma proposta diferente. No Twitter, por exemplo, o objetivo \u00e9 promover conversas entre pessoas, enquanto o Instagram funciona como uma grande plataforma para compartilhamento de fotos e v\u00eddeos.<\/p>\n<p>Quando usamos as redes sociais para promover consult\u00f3rios e cl\u00ednicas, \u00e9 muito importante conhecer as ferramentas e saber usar, da melhor forma poss\u00edvel, os recursos de cada uma delas. Afinal, seus pacientes n\u00e3o ter\u00e3o interesse em seguir o seu consult\u00f3rio em diversos canais se todos eles abordarem os mesmos temas das mesmas formas.<\/p>\n<p><strong>Saiba separar o pessoal do profissional<\/strong><\/p>\n<p>Quem trabalha na \u00e1rea sabe que a figura do profissional da sa\u00fade est\u00e1 bastante atrelada ao servi\u00e7o oferecido, ou seja, voc\u00ea \u00e9 o produto que vende. No entanto, quando falamos de usar as redes sociais como parte da divulga\u00e7\u00e3o da sua cl\u00ednica, \u00e9 muito importante que voc\u00ea saiba separar a sua vida pessoal da profissional.<\/p>\n<p>Na pr\u00e1tica, isso significa que voc\u00ea deve criar canais espec\u00edficos para falar enquanto profissional, ao inv\u00e9s de usar o seu perfil que j\u00e1 existe no Facebook para isso. Os seus pacientes n\u00e3o querem saber como foi o almo\u00e7o de domingo com a fam\u00edlia e, misturar os assuntos nas redes sociais, pode passar uma mensagem de falta de profissionalismo e afastar futuros pacientes.<\/p>\n<p><strong>Ofere\u00e7a algo que as pessoas precisem<\/strong><\/p>\n<p>As redes sociais s\u00e3o sobre conversas e informa\u00e7\u00f5es relevantes. Divulgar os diferenciais da sua cl\u00ednica \u00e9 importante, no entanto, falar apenas de si mesmo \u00e9 cansativo e n\u00e3o mantem os pacientes interessados.<\/p>\n<p>Por isso, desenvolva conte\u00fados exclusivos e altamente relevantes. Veja como voc\u00ea pode ajudar as pessoas dando dicas de sa\u00fade, cuidados com a pele, alimenta\u00e7\u00e3o, entre outros. Quando voc\u00ea oferece informa\u00e7\u00e3o de qualidade, atrai pessoas interessadas naturalmente e que, com certeza, ter\u00e3o grandes chances de procurar a sua cl\u00ednica e se tornarem pacientes!<\/p>\n<p><strong>Analise o retorno<\/strong><\/p>\n<p>Sejamos honestos: de nada adianta abrir uma nova frente de comunica\u00e7\u00e3o se voc\u00ea n\u00e3o souber, efetivamente, o retorno que ela vai te gerar. As redes sociais s\u00e3o um poderoso canal de divulga\u00e7\u00e3o e relacionamento para cl\u00ednicas, no entanto, \u00e9 preciso monitorar e avaliar todas as a\u00e7\u00f5es constantemente para que seja poss\u00edvel focar nas melhores estrat\u00e9gias.<\/p>\n<p>Esse \u00e9 um trabalho constante e que demanda tempo e conhecimento. Por isso, \u00e9 fundamental pesquisar bastante sobre o assunto e avaliar a possibilidade de contar com um profissional especializado que te oriente durante essa jornada.<\/p>\n<p>Gostou das nossas dicas? N\u00e3o esque\u00e7a de deixar um coment\u00e1rio para nos contar como a sua cl\u00ednica usa as redes sociais!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro! A seguir, vamos listar algumas dicas muito interessantes para voc\u00ea come\u00e7ar a explorar esse canal ainda hoje e conquistar novos pacientes. Entenda a proposta de cada rede Cada rede social tem uma &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/\" class=\"more-link\">Continue lendo<span class=\"screen-reader-text\"> &#8220;Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes&#8221;<\/span><\/a><\/p>\n","protected":false},"author":12,"featured_media":549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-medico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Redes sociais para conquistar novos pacientes: saiba como utilizar<\/title>\n<meta name=\"description\" content=\"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redes sociais para conquistar novos pacientes: saiba como utilizar\" \/>\n<meta property=\"og:description\" content=\"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/\" \/>\n<meta property=\"og:site_name\" content=\"GerenteWeb\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Gerenteweb\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-07-15T12:02:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-12T13:55:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"GerenteWeb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gerenteweb\" \/>\n<meta name=\"twitter:site\" content=\"@gerenteweb\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"GerenteWeb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/\"},\"author\":{\"name\":\"GerenteWeb\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/1b005ed8f788faef1d88e84fdc852cfd\"},\"headline\":\"Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes\",\"datePublished\":\"2016-07-15T12:02:38+00:00\",\"dateModified\":\"2020-11-12T13:55:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/img-33.jpg\",\"articleSection\":[\"Marketing M\u00e9dico\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/\",\"name\":\"Redes sociais para conquistar novos pacientes: saiba como utilizar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/img-33.jpg\",\"datePublished\":\"2016-07-15T12:02:38+00:00\",\"dateModified\":\"2020-11-12T13:55:19+00:00\",\"description\":\"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/img-33.jpg\",\"contentUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/img-33.jpg\",\"width\":900,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/redes-sociais-para-conquistar-novos-pacientes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\",\"name\":\"GerenteWeb\",\"description\":\"Marketing Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#organization\",\"name\":\"GerenteWeb\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo-gerenteweb.png\",\"contentUrl\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/logo-gerenteweb.png\",\"width\":229,\"height\":54,\"caption\":\"GerenteWeb\"},\"image\":{\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Gerenteweb\\\/\",\"https:\\\/\\\/x.com\\\/gerenteweb\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gerenteweb\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/1b005ed8f788faef1d88e84fdc852cfd\",\"name\":\"GerenteWeb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g\",\"caption\":\"GerenteWeb\"},\"url\":\"https:\\\/\\\/conteudo.gerenteweb.com.br\\\/blog\\\/author\\\/gerenteweb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redes sociais para conquistar novos pacientes: saiba como utilizar","description":"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/","og_locale":"pt_BR","og_type":"article","og_title":"Redes sociais para conquistar novos pacientes: saiba como utilizar","og_description":"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!","og_url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/","og_site_name":"GerenteWeb","article_publisher":"https:\/\/www.facebook.com\/Gerenteweb\/","article_published_time":"2016-07-15T12:02:38+00:00","article_modified_time":"2020-11-12T13:55:19+00:00","og_image":[{"width":900,"height":300,"url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg","type":"image\/jpeg"}],"author":"GerenteWeb","twitter_card":"summary_large_image","twitter_creator":"@gerenteweb","twitter_site":"@gerenteweb","twitter_misc":{"Written by":"GerenteWeb","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#article","isPartOf":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/"},"author":{"name":"GerenteWeb","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/person\/1b005ed8f788faef1d88e84fdc852cfd"},"headline":"Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes","datePublished":"2016-07-15T12:02:38+00:00","dateModified":"2020-11-12T13:55:19+00:00","mainEntityOfPage":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg","articleSection":["Marketing M\u00e9dico"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/","name":"Redes sociais para conquistar novos pacientes: saiba como utilizar","isPartOf":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#primaryimage"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#primaryimage"},"thumbnailUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg","datePublished":"2016-07-15T12:02:38+00:00","dateModified":"2020-11-12T13:55:19+00:00","description":"Se voc\u00ea ainda n\u00e3o usa as redes sociais como ferramenta de divulga\u00e7\u00e3o do seu consult\u00f3rio, saiba que est\u00e1 perdendo tempo \u2013 e dinheiro!","breadcrumb":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#primaryimage","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg","contentUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2016\/07\/img-33.jpg","width":900,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/redes-sociais-para-conquistar-novos-pacientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/conteudo.gerenteweb.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Redes Sociais: saiba como explorar esse canal e conquistar novos pacientes"}]},{"@type":"WebSite","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#website","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/","name":"GerenteWeb","description":"Marketing Digital","publisher":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conteudo.gerenteweb.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#organization","name":"GerenteWeb","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2015\/12\/logo-gerenteweb.png","contentUrl":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-content\/uploads\/2015\/12\/logo-gerenteweb.png","width":229,"height":54,"caption":"GerenteWeb"},"image":{"@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Gerenteweb\/","https:\/\/x.com\/gerenteweb","https:\/\/www.linkedin.com\/company\/gerenteweb"]},{"@type":"Person","@id":"https:\/\/conteudo.gerenteweb.com.br\/blog\/#\/schema\/person\/1b005ed8f788faef1d88e84fdc852cfd","name":"GerenteWeb","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e02051ad67285639be82255b4e8a9b70ccdca847d2f116011090b0d0c308b788?s=96&d=mm&r=g","caption":"GerenteWeb"},"url":"https:\/\/conteudo.gerenteweb.com.br\/blog\/author\/gerenteweb\/"}]}},"_links":{"self":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=527"}],"version-history":[{"count":2,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/527\/revisions"}],"predecessor-version":[{"id":1512,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/527\/revisions\/1512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/media\/549"}],"wp:attachment":[{"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conteudo.gerenteweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}